﻿{"id":18533,"date":"2023-06-26T11:36:16","date_gmt":"2023-06-26T09:36:16","guid":{"rendered":"https:\/\/www.ageofglorygarments.com\/?p=18533"},"modified":"2023-06-26T11:46:04","modified_gmt":"2023-06-26T09:46:04","slug":"on-any-sunday","status":"publish","type":"post","link":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/","title":{"rendered":"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p align=\"justify\">&#8220;On Any Sunday&#8221;, r\u00e9alis\u00e9 par Bruce Brown et sorti en 1971, est un documentaire l\u00e9gendaire qui a profond\u00e9ment marqu\u00e9 l&#8217;univers de la moto et continue d&#8217;inspirer les motards passionn\u00e9s. Ce film embl\u00e9matique offre un aper\u00e7u captivant de la culture moto des ann\u00e9es 70 et de la passion qui anime les adeptes de deux-roues.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;18592&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;18594&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;18596&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;18590&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<p align=\"justify\">Le contexte de l&#8217;\u00e9poque joue un r\u00f4le cl\u00e9 dans la popularit\u00e9 de &#8220;On Any Sunday&#8221;. \u00c0 cette \u00e9poque, la moto \u00e9tait en plein essor, devenant un symbole de libert\u00e9, d&#8217;aventure et de camaraderie. Le documentaire pr\u00e9sente des images saisissantes de motos en action, des courses de motocross aux balades d\u00e9contract\u00e9es sur la plage, en passant par les courses de flat-track. Il met \u00e9galement en avant les histoires et les exp\u00e9riences de pilotes passionn\u00e9s, tels que Steve McQueen, Mert Lawwill et Malcolm Smith.<\/p>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p align=\"justify\">Avec une narration captivante et une bande-son entra\u00eenante, &#8220;On Any Sunday&#8221; offre une plong\u00e9e immersive dans le monde de la moto et transmet l&#8217;excitation, la passion et l&#8217;esprit de camaraderie qui caract\u00e9risent cette culture. Le film a r\u00e9ussi \u00e0 capturer l&#8217;essence m\u00eame de la moto et \u00e0 inspirer une g\u00e9n\u00e9ration de motards.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_separator color=&#8221;custom&#8221; border_width=&#8221;3&#8243; accent_color=&#8221;#b2a36f&#8221;][vc_column_text css=&#8221;.vc_custom_1686842663035{padding-right: 10% !important;padding-left: 10% !important;}&#8221;]<\/p>\n<p style=\"color: #b2a36f; font-size: 1.5em;\" align=\"justify\"><em>Age of Glory est une marque lifestyle de v\u00eatements, inspir\u00e9e par la moto et le style vintage. Elle trouve son inspiration directe dans l&#8217;esth\u00e9tique et l&#8217;ambiance des 70s, qu&#8217;on retrouve notamment dans &#8220;On Any Sunday&#8221;. La marque puise dans l&#8217;authenticit\u00e9, l&#8217;aventure et l&#8217;esprit de camaraderie qui ont d\u00e9fini cette p\u00e9riode, en les incorporant dans ses cr\u00e9ations uniques.<\/em><\/p>\n<p>[\/vc_column_text][vc_separator color=&#8221;custom&#8221; border_width=&#8221;3&#8243; accent_color=&#8221;#b2a36f&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1687772172844{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;background-color: #b2a36f !important;}&#8221;]<\/p>\n<p style=\"color: white; font-size: 1.7em; text-align: center;\">Une s\u00e9rie de questions a \u00e9t\u00e9 pos\u00e9 \u00e0 S\u00e9bastien, le cr\u00e9ateur d&#8217;Age of Glory, afin d&#8217;en savoir plus sur l&#8217;influence qu&#8217;a eu le film sur la cr\u00e9ation de sa marque.<\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1686842360184{margin-bottom: 10px !important;}&#8221;]<\/p>\n<p style=\"color: #b2a36f; font-size: 1.6em;\" align=\"justify\"><em><strong>Quand as-tu vu \u00ab On Any Sunday \u00bb pour la premi\u00e8re fois ? Ce film a t-il contribu\u00e9 \u00e0 ta passion pour la moto d\u2019aujourd\u2019hui ?<\/strong><\/em><\/p>\n<p>[\/vc_column_text][vc_column_text]Ma passion pour la moto a \u00e9t\u00e9 d&#8217;abord nourri par une grosse frustration car mes parents \u00e9taient anti 2 roues et du coup je me suis malheureusement mis \u00e0 la moto que tardivement. J&#8217;\u00e9tais alors plus parti dans le skateboard puis le snowboard du coup. Mais j&#8217;ai toujours r\u00eav\u00e9 de cette univers dans ma jeunesse et regard\u00e9 pas mal de vid\u00e9os de MX, le SX de Bercy tous les ans&#8230;<\/p>\n<p>J&#8217;avais vu une premi\u00e8re fois ce film, il y a assez longtemps, car j&#8217;avais vu d&#8217;abord Endless Summer et je voulais donc voir cet autre film de Bruce Brown. Mais pour \u00eatre tr\u00e8s franc, la premi\u00e8re fois que je l&#8217;ai vu, j&#8217;\u00e9tais relativement jeune, il ne m&#8217;avait pas marqu\u00e9. A cette \u00e9poque je n&#8217;\u00e9tais pas forc\u00e9ment passionn\u00e9 par le vintage et donc j&#8217;avais d\u00fb trouver ces images un peu d\u00e9su\u00e8tes. Et puis je ne pratiquais pas la moto encore malheureusement.<\/p>\n<p>C&#8217;est lorsque je l&#8217;ai revu plus tard, que j&#8217;ai ador\u00e9. J&#8217;avais entre temps enfin pu me mettre \u00e0 la moto et conna\u00eetre les sensations des 2 roues. Mon go\u00fbt du vintage s&#8217;\u00e9tait aussi affirm\u00e9. Du coup ce second visionnage avait \u00e9t\u00e9 beaucoup plus marquant pour moi. J&#8217;avais tout ador\u00e9: l&#8217;esprit cool de cette \u00e9poque, le sentiment de libert\u00e9, l&#8217;atmosph\u00e8re autour des roulages ou courses et puis aussi beaucoup le style de l&#8217;\u00e9poque, aussi bien les v\u00eatements et que les motos.<\/p>\n<p>C&#8217;est \u00e9galement On Any Sunday qui m&#8217;a pouss\u00e9 aussi \u00e0 d\u00e9couvrir le Flat Track ! Voir Mert et les autres rouler \u00e0 fond, en glissade, \u00e7a me donnait vraiment envie d&#8217;essayer. Et pour moi, avec mon pass\u00e9 tr\u00e8s li\u00e9 \u00e0 la glisse (skate et snowboard particuli\u00e8rement), cela avait du sens. Retrouver des sensations de glisse mais en moto. Ca m&#8217;a aussi pouss\u00e9 \u00e0 monter l&#8217;association de Flat Track &#8220;Vintage Racing Spirit&#8221; avec mon pote Domice.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1686842377185{margin-bottom: 10px !important;}&#8221;]<\/p>\n<p style=\"color: #b2a36f; font-size: 1.6em;\" align=\"justify\"><strong><em>Peux-tu partager une anecdote ou une exp\u00e9rience personnelle o\u00f9 le documentaire a jou\u00e9 un r\u00f4le direct dans la cr\u00e9ation d&#8217;un produit ou d&#8217;une collection pour Age of Glory ?<\/em><\/strong><\/p>\n<p>[\/vc_column_text][vc_column_text]Mon inspiration directe de ce film, c&#8217;est ma s\u00e9rie &#8220;Legendary&#8221;, pour laquelle je travaille sur des motos l\u00e9gendaires. J&#8217;ai commenc\u00e9 par certaines que l&#8217;on voit dans le film. J&#8217;avais \u00e9galement fait un poster des motos des 3 pilotes qui sont mis en avant dans le film. Il a eu fort succ\u00e8s d&#8217;ailleurs.<\/p>\n<p>Mais comme pour toute inspiration, il y a probablement une part d&#8217;inconscient et ce film, mais aussi toutes les images que j&#8217;ai pu voir de cette \u00e9poque, mont forc\u00e9ment inspir\u00e9 plus que ce que je ne le pense.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1686907636621{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;background-color: #b2a36f !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;18223&#8243; img_size=&#8221;500&#215;500&#8243; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;.vc_custom_1686907836546{padding-top: 20px !important;padding-right: 40px !important;padding-bottom: 20px !important;padding-left: 20px !important;}&#8221;]<\/p>\n<p style=\"color: white; font-size: 1.8em;\"><em>&#8221;J\u2019avais vu une premi\u00e8re fois ce film, il y a assez longtemps, (&#8230;) Mais pour \u00eatre tr\u00e8s franc, la premi\u00e8re fois que je l\u2019ai vu, j\u2019\u00e9tais relativement jeune, il ne m\u2019avait pas marqu\u00e9. A cette \u00e9poque je n\u2019\u00e9tais pas forc\u00e9ment passionn\u00e9 par le vintage et donc j\u2019avais d\u00fb trouver ces images un peu d\u00e9su\u00e8tes. Et puis je ne pratiquais pas la moto encore malheureusement.<\/em><\/p>\n<p style=\"color: white; font-size: 1.8em;\"><em>C\u2019est lorsque je l\u2019ai revu plus tard, que j\u2019ai ador\u00e9. (&#8230;) J\u2019avais tout ador\u00e9: l\u2019esprit cool de cette \u00e9poque, le sentiment de libert\u00e9, l\u2019atmosph\u00e8re autour des roulages ou courses et puis aussi beaucoup le style de l\u2019\u00e9poque, aussi bien les v\u00eatements et que les motos.&#8221;\u00a0<\/em><\/p>\n<p style=\"color: white; font-size: 1.3em;\"><em>Sebastien, cr\u00e9ateur de Age of Glory<\/em><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column css=&#8221;.vc_custom_1686845877999{margin-top: 30px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1686842388435{margin-bottom: 10px !important;}&#8221;]<\/p>\n<p style=\"color: #b2a36f; font-size: 1.6em;\" align=\"justify\"><em><strong>En regardant des photos de tes shooting, on peut trouver une similarit\u00e9 entre tes images et celles du documentaire. Est-ce une volont\u00e9 de ta part ou un hasard\u00a0?<\/strong><\/em><\/p>\n<p>[\/vc_column_text][vc_column_text]Effectivement c&#8217;est marrant de voir ces similitudes sur les images mises en exergue. Mais honn\u00eatement non. Lors des diff\u00e9rents shootings photo ou vid\u00e9o, je n&#8217;ai jamais demand\u00e9 sp\u00e9cifiquement \u00e0 recr\u00e9er telle image ou sc\u00e8ne. Ce n&#8217;\u00e9tait absolument pas le but.<\/p>\n<p>Les 70s et On Any Sunday sont une inspiration, mais cela doit rester une inspiration. Ce n&#8217;est pas non plus une obsession. Le but \u00e9tait de raconter ma propre histoire de passionn\u00e9 \u00e0 travers Age of Glory avec des inspirations 70s mais pour des riders d&#8217;aujourd&#8217;hui.<\/p>\n<p>Apr\u00e8s cela reste des sc\u00e8nes assez fr\u00e9quentes lorsqu&#8217;on pratique la moto enduro ou flat track&#8230; La similitude vient plus du style vintage.[\/vc_column_text][vc_single_image image=&#8221;18613&#8243; img_size=&#8221;Full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1686835959586{margin-bottom: 0px !important;border-bottom-width: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_single_image image=&#8221;18615&#8243; img_size=&#8221;Full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1686835986400{margin-top: 0px !important;margin-bottom: 0px !important;border-top-width: 0px !important;border-bottom-width: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_single_image image=&#8221;18617&#8243; img_size=&#8221;Full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1686836010883{margin-top: 0px !important;border-top-width: 0px !important;padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1686842399821{margin-bottom: 10px !important;}&#8221;]<\/p>\n<p style=\"color: #b2a36f; font-size: 1.6em;\" align=\"justify\"><strong><em>Le documentaire met en avant des personnages embl\u00e9matiques de la moto tels que Steve McQueen, Mert Lawwill et Malcolm Smith. Selon toi, le quel de ces trois repr\u00e9sente le plus l\u2019univers d\u2019Age of Glory ?<\/em><\/strong><\/p>\n<p>[\/vc_column_text][vc_column_text]C&#8217;est difficile car je pense qu&#8217;ils ont tous int\u00e9ressants \u00e0 mes yeux mais pour des raisons tr\u00e8s diff\u00e9rentes.<\/p>\n<p>Le plus connu est bien entendu Steve. Ce qui m&#8217;int\u00e9resse chez lui c&#8217;est que malgr\u00e9 la popularit\u00e9 qu&#8217;il avait \u00e0 l&#8217;\u00e9poque, on pouvait le retrouver au d\u00e9part d&#8217;une course d&#8217;enduro presque en anonyme. Je pense qu&#8217;il avait une r\u00e9elle passion pour la moto et a s\u00fbrement contribu\u00e9 \u00e0 rendre la moto plus populaire aussi \u00e0 travers certains de ses films et ses participations \u00e0 des courses mythiques. Il avait aussi un style unique. Humainement, c&#8217;\u00e9tait une personnalit\u00e9 un peu complexe je pense, et malgr\u00e9 le fait qu&#8217;il \u00e9tait per\u00e7u comme le king of cool, je ne sais pas si il portait bien ce pseudo tout le temps<\/p>\n<p>Forc\u00e9ment Mert Lawill, et mon attrait pour le flat track, semble \u00eatre un personnage tout trouv\u00e9 pour repr\u00e9senter au mieux la marque mais je pense que Malcolm Smith est pour moi une plus belle repr\u00e9sentation. J&#8217;avais d&#8217;ailleurs fait un petit article sur lui en r\u00e9f\u00e9rence \u00e0 un article de motorcyclistonline.com (\u00e0 voir <a href=\"https:\/\/www.ageofglorygarments.com\/malcolm-smith-the-man-who-changed-motorcycling\/\">ici<\/a>). Ce fut un pilote hors pair, humble et discret&#8230; Et pourtant je pense qu&#8217;au guidon d&#8217;une moto il avait peu d&#8217;\u00e9gal.[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"color: #b2a36f; text-align: center;\"><strong>\u2193 Style vintage inspir\u00e9 des pilotes des 70s. \u2193<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;12881&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.ageofglorygarments.com\/fr\/product\/heritage-raglan-ls-tee-royal-blue-off-white-red\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;8657&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.ageofglorygarments.com\/fr\/product\/desert-pant-ce-sand\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;14877&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.ageofglorygarments.com\/fr\/product\/gants-hero-ce-cuir-bleu-rouge-blanc\/&#8221;][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;12849&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;custom_link&#8221; link=&#8221;https:\/\/www.ageofglorygarments.com\/fr\/product\/legendary-bikes-neck-tube\/&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_separator color=&#8221;custom&#8221; border_width=&#8221;10&#8243; accent_color=&#8221;#b2a36f&#8221;][vc_column_text]<\/p>\n<h3>On Any Sunday: le Film de 1971<\/h3>\n<p>[\/vc_column_text][vc_column_text]Si vous ne l&#8217;avez toujours pas vu, c&#8217;est le moment de prendre enfin le temps de le faire![\/vc_column_text][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=4H9xfKW0zJE&#8221; align=&#8221;center&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_separator color=&#8221;custom&#8221; border_width=&#8221;10&#8243; accent_color=&#8221;#b2a36f&#8221;][vc_column_text]<\/p>\n<h3>On Any Sunday: The Next Chapter<\/h3>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;18629&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<p>Apr\u00e8s le succ\u00e8s retentissant de &#8220;On Any Sunday&#8221;, une suite intitul\u00e9e &#8220;On Any Sunday 2&#8221; a vu le jour en 1981. Ce film a \u00e9t\u00e9 r\u00e9alis\u00e9 par le fils de Bruce Brown, Dana Brown, qui a suivi les traces de son p\u00e8re pour explorer davantage la culture moto et les aventures qui l&#8217;entourent.<\/p>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p><strong><em>On Any Sunday: The Next Chapter<\/em><\/strong> perp\u00e9tue l&#8217;esprit du film original en mettant en lumi\u00e8re diff\u00e9rents aspects de la moto et en mettant en avant des pilotes passionn\u00e9s et des \u00e9v\u00e9nements majeurs. Le documentaire offre un regard captivant sur les courses de motocross, les courses d&#8217;endurance, les courses de d\u00e9sert et d&#8217;autres formes de comp\u00e9tition moto qui suscitent l&#8217;excitation des fans.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=-3QcBIOWtgo&#8221; align=&#8221;center&#8221;][vc_separator color=&#8221;custom&#8221; border_width=&#8221;10&#8243; accent_color=&#8221;#b2a36f&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1686844982141{margin-top: 20px !important;padding-top: 10px !important;}&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;18573&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;2\/3&#8243; css=&#8221;.vc_custom_1686758248206{padding-right: 10% !important;}&#8221;][vc_column_text]<\/p>\n<h2>The Endless Summer: l&#8217;autre film embl\u00e9matique de Bruce Brown<\/h2>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p align=\"justify\">Bruce Brown, le r\u00e9alisateur de &#8220;On Any Sunday&#8221;, est une figure embl\u00e9matique du cin\u00e9ma documentaire li\u00e9 \u00e0 la culture de la moto et du surf. Son influence ne s\u2019arr\u00eate pas seulement \u00e0 ce film et s&#8217;\u00e9tend \u00e0 d&#8217;autres r\u00e9alisations marquantes, notamment &#8220;The Endless Summer&#8221;.<\/p>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p align=\"justify\">&#8220;The Endless Summer&#8221; (1966) est un film documentaire marquant qui a profond\u00e9ment influenc\u00e9 la culture du surf. Ce film embl\u00e9matique suit deux surfeurs, Mike Hynson et Robert August, dans leur qu\u00eate \u00e0 travers le monde \u00e0 la recherche des vagues parfaites et de l&#8217;\u00e9t\u00e9 \u00e9ternel.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] &#8220;On Any Sunday&#8221;, r\u00e9alis\u00e9 par Bruce Brown et sorti en 1971, est un documentaire l\u00e9gendaire qui a profond\u00e9ment marqu\u00e9 l&#8217;univers de la moto et&hellip;<\/p>\n","protected":false},"author":1,"featured_media":18759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration - Age of Glory<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration - Age of Glory\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] &#8220;On Any Sunday&#8221;, r\u00e9alis\u00e9 par Bruce Brown et sorti en 1971, est un documentaire l\u00e9gendaire qui a profond\u00e9ment marqu\u00e9 l&#8217;univers de la moto et&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/\" \/>\n<meta property=\"og:site_name\" content=\"Age of Glory\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/ageofglorygarments\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-26T09:36:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T09:46:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.ageofglorygarments.com\/wp-content\/uploads\/2023\/06\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Sebastien Age of Glory\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastien Age of Glory\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/\"},\"author\":{\"name\":\"Sebastien Age of Glory\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/#\\\/schema\\\/person\\\/c1dbdf6f401bde177d47e68b39945370\"},\"headline\":\"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration\",\"datePublished\":\"2023-06-26T09:36:16+00:00\",\"dateModified\":\"2023-06-26T09:46:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/\"},\"wordCount\":2360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.ageofglorygarments.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/\",\"url\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/\",\"name\":\"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration - Age of Glory\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.ageofglorygarments.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1\",\"datePublished\":\"2023-06-26T09:36:16+00:00\",\"dateModified\":\"2023-06-26T09:46:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.ageofglorygarments.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.ageofglorygarments.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/on-any-sunday\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/#website\",\"url\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/\",\"name\":\"Age of Glory\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/#organization\",\"name\":\"Age of Glory\",\"url\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/tee-graphics-logo-sand.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/tee-graphics-logo-sand.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Age of Glory\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/ageofglorygarments\",\"http:\\\/\\\/www.instagram.com\\\/ageofglorygarments\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/#\\\/schema\\\/person\\\/c1dbdf6f401bde177d47e68b39945370\",\"name\":\"Sebastien Age of Glory\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/wp-content\\\/litespeed\\\/avatar\\\/8e93ba024ca82d6202d57e57e7c311f5.jpg?ver=1778259250\",\"url\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/wp-content\\\/litespeed\\\/avatar\\\/8e93ba024ca82d6202d57e57e7c311f5.jpg?ver=1778259250\",\"contentUrl\":\"https:\\\/\\\/www.ageofglorygarments.com\\\/wp-content\\\/litespeed\\\/avatar\\\/8e93ba024ca82d6202d57e57e7c311f5.jpg?ver=1778259250\",\"caption\":\"Sebastien Age of Glory\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration - Age of Glory","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/","og_locale":"fr_FR","og_type":"article","og_title":"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration - Age of Glory","og_description":"[vc_row][vc_column][vc_column_text] &#8220;On Any Sunday&#8221;, r\u00e9alis\u00e9 par Bruce Brown et sorti en 1971, est un documentaire l\u00e9gendaire qui a profond\u00e9ment marqu\u00e9 l&#8217;univers de la moto et&hellip;","og_url":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/","og_site_name":"Age of Glory","article_publisher":"http:\/\/www.facebook.com\/ageofglorygarments","article_published_time":"2023-06-26T09:36:16+00:00","article_modified_time":"2023-06-26T09:46:04+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/i0.wp.com\/www.ageofglorygarments.com\/wp-content\/uploads\/2023\/06\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1","type":"image\/webp"}],"author":"Sebastien Age of Glory","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sebastien Age of Glory","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/#article","isPartOf":{"@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/"},"author":{"name":"Sebastien Age of Glory","@id":"https:\/\/www.ageofglorygarments.com\/#\/schema\/person\/c1dbdf6f401bde177d47e68b39945370"},"headline":"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration","datePublished":"2023-06-26T09:36:16+00:00","dateModified":"2023-06-26T09:46:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/"},"wordCount":2360,"commentCount":0,"publisher":{"@id":"https:\/\/www.ageofglorygarments.com\/#organization"},"image":{"@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.ageofglorygarments.com\/wp-content\/uploads\/2023\/06\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/","url":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/","name":"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration - Age of Glory","isPartOf":{"@id":"https:\/\/www.ageofglorygarments.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/#primaryimage"},"image":{"@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.ageofglorygarments.com\/wp-content\/uploads\/2023\/06\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1","datePublished":"2023-06-26T09:36:16+00:00","dateModified":"2023-06-26T09:46:04+00:00","breadcrumb":{"@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/#primaryimage","url":"https:\/\/i0.wp.com\/www.ageofglorygarments.com\/wp-content\/uploads\/2023\/06\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.ageofglorygarments.com\/wp-content\/uploads\/2023\/06\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.ageofglorygarments.com\/fr\/on-any-sunday\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ageofglorygarments.com\/fr\/"},{"@type":"ListItem","position":2,"name":"On Any Sunday: Le film inspirant de toute une g\u00e9n\u00e9ration"}]},{"@type":"WebSite","@id":"https:\/\/www.ageofglorygarments.com\/#website","url":"https:\/\/www.ageofglorygarments.com\/","name":"Age of Glory","description":"","publisher":{"@id":"https:\/\/www.ageofglorygarments.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ageofglorygarments.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ageofglorygarments.com\/#organization","name":"Age of Glory","url":"https:\/\/www.ageofglorygarments.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ageofglorygarments.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ageofglorygarments.com\/wp-content\/uploads\/2018\/01\/tee-graphics-logo-sand.jpg","contentUrl":"https:\/\/www.ageofglorygarments.com\/wp-content\/uploads\/2018\/01\/tee-graphics-logo-sand.jpg","width":1200,"height":1200,"caption":"Age of Glory"},"image":{"@id":"https:\/\/www.ageofglorygarments.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/ageofglorygarments","http:\/\/www.instagram.com\/ageofglorygarments"]},{"@type":"Person","@id":"https:\/\/www.ageofglorygarments.com\/#\/schema\/person\/c1dbdf6f401bde177d47e68b39945370","name":"Sebastien Age of Glory","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ageofglorygarments.com\/wp-content\/litespeed\/avatar\/8e93ba024ca82d6202d57e57e7c311f5.jpg?ver=1778259250","url":"https:\/\/www.ageofglorygarments.com\/wp-content\/litespeed\/avatar\/8e93ba024ca82d6202d57e57e7c311f5.jpg?ver=1778259250","contentUrl":"https:\/\/www.ageofglorygarments.com\/wp-content\/litespeed\/avatar\/8e93ba024ca82d6202d57e57e7c311f5.jpg?ver=1778259250","caption":"Sebastien Age of Glory"}}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.ageofglorygarments.com\/wp-content\/uploads\/2023\/06\/on-any-sunday-1971-moto-movie-ageofglory.webp?fit=1920%2C1080&ssl=1","_links":{"self":[{"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/posts\/18533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/comments?post=18533"}],"version-history":[{"count":0,"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/posts\/18533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/media\/18759"}],"wp:attachment":[{"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/media?parent=18533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/categories?post=18533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ageofglorygarments.com\/fr\/wp-json\/wp\/v2\/tags?post=18533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}